{"id":1552,"date":"2024-01-24T08:28:05","date_gmt":"2024-01-24T08:28:05","guid":{"rendered":"https:\/\/comfortesq-lombo.savviihq.com\/?post_type=changelog&#038;p=1552"},"modified":"2026-03-13T10:40:20","modified_gmt":"2026-03-13T10:40:20","slug":"version-4-111","status":"publish","type":"changelog","link":"https:\/\/fortesquojob.com\/de\/changeloggs\/version-4-111\/","title":{"rendered":"Version 4.111"},"content":{"rendered":"\n<div class=\"post-content\">\n\n  <h2 style=\"color:#2CACE3!important;\">Jobs<\/h2>\n  <ul>\n    <li>\u00dcberarbeiteter Leistungsnachweis.<\/li>\n    <li>U.a. wurde im Leistungsnachweis die Userf\u00fchrung anhand von ausgegrauten Buttons und Warnmeldungen verbessert.<\/li>\n    <li>Im neuen Leistungsnachweis-PDF kann man nun individuelle Seitenumbr\u00fcche einstellen.<\/li>\n    <li>Retainer: Im Retainer Report ist die Datumsselektion &#8222;bis&#8220; jetzt inklusive.<\/li>\n    <li>Die Zeile f\u00fcr &#8222;W\u00e4hrung&#8220; in Mediaschaltungen besitzt nun auch einen Link zum W\u00e4hrungsrechner wie in Angeboten.<\/li>\n  <\/ul>\n\n  <h2 style=\"color:#2CACE3!important;\">MyDay<\/h2>\n  <ul>\n    <li>Neuer Kalender.<\/li>\n    <li>+ Button f\u00fcr Aufgabenanlage im MyDay-Widget &#8222;Aufgaben&#8220;.<\/li>\n  <\/ul>\n\n  <h2 style=\"color:#2CACE3!important;\">PM Professional<\/h2>\n  <ul>\n    <li>Kapazit\u00e4t wird jetzt bei der Aufgabenanlage ausgewiesen.<\/li>\n    <li>Benutzer mit PM-Recht auf &#8222;Lesen&#8220; d\u00fcrfen nun auch Unteraufgaben anlegen, wenn die Aufgabe nicht von ihnen selbst erstellt wurde, sondern an sie delegiert wurde, wenn die Admin-Option &#8222;Aufgaben f\u00fcr sich selbst anlegen&#8220; daf\u00fcr aktiv ist.<\/li>\n    <li>Job-Filter in der Mitarbeiter-Kapa-Ansicht im PM Professional.<\/li>\n    <li>Wird eine Jobvorlage importiert, werden auch die Aufgaben der Vorlage kopiert. Aufgabenhierarchien bleiben dabei bestehen. Es werden allerdings keine Links, keine Kommunikation und keine Dateien, Termine etc. kopiert. Das Start- und Enddatum der kopierten Aufgabe wird im Verh\u00e4ltnis zum neuen Startdatum berechnet.<\/li>\n  <\/ul>\n\n  <h2 style=\"color:#2CACE3!important;\">Kontakte<\/h2>\n  <ul>\n    <li>Eingangsrechnungen und Zahlungen im Kontakt -> Historie verlinkt.<\/li>\n    <li>Die Kontakthistorie zeigt nun die Jobs f\u00fcr Eingangsrechnungen und Zahlungen von Eingangsrechnungen an.<\/li>\n  <\/ul>\n\n  <h2 style=\"color:#2CACE3!important;\">Buchhaltung<\/h2>\n  <ul>\n    <li>Belegliste Eingangsrechnung: Zus\u00e4tzliche Option &#8222;Abgelehnt&#8220; bei Filter Freigabestatus.<\/li>\n    <li>FiBu Export: Nicht generierte PDFs werden als Fehler angezeigt.<\/li>\n    <li>Wird eine Adresse ge\u00e4ndert, die bereits auf einer Rechnung existiert, wird stattdessen die bisherige Adresse deaktiviert und eine neue Adresse erstellt. Noch nicht erstellte WKRs, Akonto- und Fakturenvorschl\u00e4ge werden auf die neue Adresse aktualisiert.<\/li>\n    <li>FiBu Export: Performance-Verbesserungen.<\/li>\n    <li>Der Stornodialog f\u00fcr Ausgangsrechnungen zeigt nun eine Fehlermeldung, wenn das Datum von bestehenden Storno-Rechnungen bei einer \u00c4nderung den aktuellen Nummernkreis \u00e4ndern w\u00fcrde.<\/li>\n    <li>Der Dialog f\u00fcr Akontorechnungen zeigt nun eine Fehlermeldung, wenn das Datum von bestehenden Rechnungen bei einer \u00c4nderung den aktuellen Nummernkreis \u00e4ndern w\u00fcrde.<\/li>\n    <li>Der Stornodialog f\u00fcr Akontorechnungen zeigt nun eine Fehlermeldung, wenn das Datum von bestehenden Storno-Rechnungen bei einer \u00c4nderung den aktuellen Nummernkreis \u00e4ndern w\u00fcrde.<\/li>\n  <\/ul>\n\n  <h2 style=\"color:#2CACE3!important;\">Controlling<\/h2>\n  <ul>\n    <li>Neue optionale Spalte KSK f\u00fcr den Report &#8222;Ausgangsrechnung&#8220;.<\/li>\n    <li>Summendarstellung funktioniert im Report &#8222;Detaillierte Jobstunden&#8220; nun auch im CSV-Export.<\/li>\n  <\/ul>\n\n  <h2 style=\"color:#2CACE3!important;\">Admin<\/h2>\n  <ul>\n    <li>Dateinamen f\u00fcr Briefb\u00f6gen d\u00fcrfen nun mehr Zeichen als 40 haben -> 200.<\/li>\n    <li>E-Mail-Adresse f\u00fcr Buchhaltungsbelege im Admin-Bereich kann jetzt mandantengetrennt gespeichert werden.<\/li>\n  <\/ul>\n\n  <h2 style=\"color:#2CACE3!important;\">REST-API<\/h2>\n  <ul>\n    <li>Feature Endpunkt f\u00fcr Ausgangsrechnungen.<\/li>\n    <li>Neues API-Objekt f\u00fcr Rechnungseinstellungen.<\/li>\n    <li>Neues API-Objekt f\u00fcr Rechnungspositionen.<\/li>\n    <li>Neues API-Objekt f\u00fcr Rechnungsjobs.<\/li>\n    <li>Neues API-Objekt f\u00fcr Rechnungsheadlines.<\/li>\n  <\/ul>\n\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Jobs \u00dcberarbeiteter Leistungsnachweis. U.a. wurde im Leistungsnachweis die Userf\u00fchrung anhand von ausgegrauten Buttons und Warnmeldungen verbessert. Im neuen Leistungsnachweis-PDF kann man nun individuelle Seitenumbr\u00fcche einstellen. Retainer: Im Retainer Report ist die Datumsselektion &#8222;bis&#8220; jetzt inklusive. Die Zeile f\u00fcr &#8222;W\u00e4hrung&#8220; in Mediaschaltungen besitzt nun auch einen Link zum W\u00e4hrungsrechner wie in Angeboten. MyDay Neuer Kalender. + [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","changelog_tags":[],"class_list":["post-1552","changelog","type-changelog","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Version 4.111 - QuoJob<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fortesquojob.com\/de\/changeloggs\/version-4-111\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Version 4.111 - QuoJob\" \/>\n<meta property=\"og:description\" content=\"Jobs \u00dcberarbeiteter Leistungsnachweis. U.a. wurde im Leistungsnachweis die Userf\u00fchrung anhand von ausgegrauten Buttons und Warnmeldungen verbessert. Im neuen Leistungsnachweis-PDF kann man nun individuelle Seitenumbr\u00fcche einstellen. Retainer: Im Retainer Report ist die Datumsselektion &#8222;bis&#8220; jetzt inklusive. Die Zeile f\u00fcr &#8222;W\u00e4hrung&#8220; in Mediaschaltungen besitzt nun auch einen Link zum W\u00e4hrungsrechner wie in Angeboten. MyDay Neuer Kalender. + [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fortesquojob.com\/de\/changeloggs\/version-4-111\/\" \/>\n<meta property=\"og:site_name\" content=\"QuoJob\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-13T10:40:20+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fortesquojob.com\\\/de\\\/changeloggs\\\/version-4-111\\\/\",\"url\":\"https:\\\/\\\/fortesquojob.com\\\/de\\\/changeloggs\\\/version-4-111\\\/\",\"name\":\"Version 4.111 - QuoJob\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fortesquojob.com\\\/de\\\/#website\"},\"datePublished\":\"2024-01-24T08:28:05+00:00\",\"dateModified\":\"2026-03-13T10:40:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fortesquojob.com\\\/de\\\/changeloggs\\\/version-4-111\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fortesquojob.com\\\/de\\\/changeloggs\\\/version-4-111\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fortesquojob.com\\\/de\\\/changeloggs\\\/version-4-111\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Start\",\"item\":\"https:\\\/\\\/fortesquojob.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Changelogs\",\"item\":\"https:\\\/\\\/fortesquojob.com\\\/de\\\/changeloggs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Version 4.111\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fortesquojob.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/fortesquojob.com\\\/de\\\/\",\"name\":\"QuoJob\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fortesquojob.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Version 4.111 - QuoJob","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fortesquojob.com\/de\/changeloggs\/version-4-111\/","og_locale":"de_DE","og_type":"article","og_title":"Version 4.111 - QuoJob","og_description":"Jobs \u00dcberarbeiteter Leistungsnachweis. U.a. wurde im Leistungsnachweis die Userf\u00fchrung anhand von ausgegrauten Buttons und Warnmeldungen verbessert. Im neuen Leistungsnachweis-PDF kann man nun individuelle Seitenumbr\u00fcche einstellen. Retainer: Im Retainer Report ist die Datumsselektion &#8222;bis&#8220; jetzt inklusive. Die Zeile f\u00fcr &#8222;W\u00e4hrung&#8220; in Mediaschaltungen besitzt nun auch einen Link zum W\u00e4hrungsrechner wie in Angeboten. MyDay Neuer Kalender. + [&hellip;]","og_url":"https:\/\/fortesquojob.com\/de\/changeloggs\/version-4-111\/","og_site_name":"QuoJob","article_modified_time":"2026-03-13T10:40:20+00:00","twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fortesquojob.com\/de\/changeloggs\/version-4-111\/","url":"https:\/\/fortesquojob.com\/de\/changeloggs\/version-4-111\/","name":"Version 4.111 - QuoJob","isPartOf":{"@id":"https:\/\/fortesquojob.com\/de\/#website"},"datePublished":"2024-01-24T08:28:05+00:00","dateModified":"2026-03-13T10:40:20+00:00","breadcrumb":{"@id":"https:\/\/fortesquojob.com\/de\/changeloggs\/version-4-111\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fortesquojob.com\/de\/changeloggs\/version-4-111\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fortesquojob.com\/de\/changeloggs\/version-4-111\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Start","item":"https:\/\/fortesquojob.com\/de\/"},{"@type":"ListItem","position":2,"name":"Changelogs","item":"https:\/\/fortesquojob.com\/de\/changeloggs\/"},{"@type":"ListItem","position":3,"name":"Version 4.111"}]},{"@type":"WebSite","@id":"https:\/\/fortesquojob.com\/de\/#website","url":"https:\/\/fortesquojob.com\/de\/","name":"QuoJob","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fortesquojob.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/fortesquojob.com\/de\/wp-json\/wp\/v2\/changelog\/1552","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fortesquojob.com\/de\/wp-json\/wp\/v2\/changelog"}],"about":[{"href":"https:\/\/fortesquojob.com\/de\/wp-json\/wp\/v2\/types\/changelog"}],"author":[{"embeddable":true,"href":"https:\/\/fortesquojob.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/fortesquojob.com\/de\/wp-json\/wp\/v2\/comments?post=1552"}],"wp:attachment":[{"href":"https:\/\/fortesquojob.com\/de\/wp-json\/wp\/v2\/media?parent=1552"}],"wp:term":[{"taxonomy":"changelog_tags","embeddable":true,"href":"https:\/\/fortesquojob.com\/de\/wp-json\/wp\/v2\/changelog_tags?post=1552"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}